{"id":10343,"date":"2026-06-25T11:55:32","date_gmt":"2026-06-25T09:55:32","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/produktionsmitarbeiter-im-metallbereich-fuer-raum-lilienfeld-gesucht-m-w-d-19603\/"},"modified":"2026-07-15T15:56:05","modified_gmt":"2026-07-15T13:56:05","slug":"produktionsmitarbeiter-im-metallbereich-fuer-raum-lilienfeld-gesucht-m-w-d-19603","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/produktionsmitarbeiter-im-metallbereich-fuer-raum-lilienfeld-gesucht-m-w-d-19603\/","title":{"rendered":"Produktionsmitarbeiter im Metallbereich f\u00fcr Raum Lilienfeld gesucht (m\/w\/d)"},"excerpt":{"rendered":"<p>Wir suchen f\u00fcr unseren Kunden Produktionsmitarbeiter im Metallbereich f\u00fcr Raum 3180 Lilienfeld (m\/w\/d) zum ehestm\u00f6glichen Eintritt. Aufgabenbereiche: &#8211; Best\u00fcckung von Maschinen &#8211; Bedienung von Maschinen und Anlagen &#8211; Kontrollt\u00e4tigkeiten nach Anweisung &#8211; allgemeine Hilfst\u00e4tigkeiten &#8211; Metallbearbeitung Qualifikationen und Anforderungen: &#8211; Berufserfahrung als Produktionsarbeiter (m\/w\/d) erw\u00fcnscht &#8211; K\u00f6rperliche Fitness sowie Belastbarkeit &#8211; Einsatzbereitschaft, Zuverl\u00e4ssigkeit und Teamf\u00e4higkeit [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10343","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}