{"id":10299,"date":"2026-06-17T11:15:28","date_gmt":"2026-06-17T09:15:28","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/eventmitarbeiterin-im-servicebereich-m-w-d-19562\/"},"modified":"2026-07-15T11:55:26","modified_gmt":"2026-07-15T09:55:26","slug":"eventmitarbeiterin-im-servicebereich-m-w-d-19562","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/eventmitarbeiterin-im-servicebereich-m-w-d-19562\/","title":{"rendered":"Eventmitarbeiter:in im Servicebereich (m\/w\/d)"},"excerpt":{"rendered":"<p>Wir suchen f\u00fcr unseren Kunden in Wien eine(n) Eventmitarbeiter:in im Servicebereich (m\/w\/d) auf geringf\u00fcgiger Basis zum ehestm\u00f6glichen Eintritt. Aufgabenbereiche: &#8211; Mitarbeit bei Events im Servicebereich &#8211; Servieren von Speisen und Getr\u00e4nken &#8211; G\u00e4steempfang und -betreuung &#8211; Vor- und Nachbereitungsarbeiten &#8211; Mithilfe bei Auf- und Abbau sowie laufende Koordination von Events &#8211; Einhaltung der Hygienevorschriften Qualifikationen [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10299","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}