{"id":10239,"date":"2026-05-29T14:54:32","date_gmt":"2026-05-29T12:54:32","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/servicemitarbeiterin-werde-teil-unseres-event-teams-m-w-d-19506\/"},"modified":"2026-07-15T11:36:24","modified_gmt":"2026-07-15T09:36:24","slug":"servicemitarbeiterin-werde-teil-unseres-event-teams-m-w-d-19506","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/servicemitarbeiterin-werde-teil-unseres-event-teams-m-w-d-19506\/","title":{"rendered":"ServicemitarbeiterIn\/Werde Teil unseres Event-Teams! (m\/w\/d)"},"excerpt":{"rendered":"<p>Bist du bereit, bei den aufregendsten Events in einer der exklusivsten Eventlocations von ganz Wien mitzuarbeiten? Wir suchen nach motivierten und interessierte StudentInnen (m\/w\/d), die unser Service-Team verst\u00e4rken wollen. Wenn du Lust auf flexible Arbeitszeiten, ein dynamisches Arbeitsumfeld und jede Menge Spa\u00df hast, dann bist du bei uns genau richtig! Aufgabenbereiche: &#8211; Rocke die Events: [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10239","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}