{"id":10221,"date":"2026-05-28T14:14:33","date_gmt":"2026-05-28T12:14:33","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/customer-service-administrator-m-w-d-19487\/"},"modified":"2026-07-15T10:35:25","modified_gmt":"2026-07-15T08:35:25","slug":"customer-service-administrator-m-w-d-19487","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/customer-service-administrator-m-w-d-19487\/","title":{"rendered":"Customer Service Administrator (m\/w\/d)"},"excerpt":{"rendered":"<p>Wir suchen f\u00fcr unseren Kunden in 1230 Wien eine(n) Customer Service Administrator (m\/w\/d) zum ehestm\u00f6glichen Eintritt. Aufgabenbereiche: &#8211; Schnittstellenfunkton zu Montageleiter*innen &#8211; Administrative Unterst\u00fctzung des Service-Au\u00dfendienstes &#8211; Material-Management &#8211; Workflow Bearbeitung &#8211; Pr\u00fcfung und Festlegung zu erbrachten Leistungen &#8211; Disponierung von Auftr\u00e4gen und Bearbeitung im System &#8211; Terminkoordination Qualifikationen und Anforderungen: &#8211; Abgeschlossene Ausbildung im [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10221","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}