{"id":10190,"date":"2026-05-21T09:54:35","date_gmt":"2026-05-21T07:54:35","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/personalverrechnerin-m-w-d-19456\/"},"modified":"2026-07-15T10:35:24","modified_gmt":"2026-07-15T08:35:24","slug":"personalverrechnerin-m-w-d-19456","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/personalverrechnerin-m-w-d-19456\/","title":{"rendered":"Personalverrechner*in (m\/w\/d)"},"excerpt":{"rendered":"<p>Wir suchen f\u00fcr unseren Kunden in Wien eine*n Personalverrechner*in (m\/w\/d) zum ehestm\u00f6glichen Eintritt. Aufgabenbereiche: &#8211; Selbst\u00e4ndige Lohn- und Gehaltsverrechnung innerhalb der Firmengruppe mit Sage &#8211; Anwendung des Metall-KVs &#8211; Verwaltung von arbeitszeitlichen und entgeltlichen Anspr\u00fcchen &#8211; Verwaltung der Personalstammdaten &#8211; Erstellung von Statistiken und Auswertungen &#8211; Firmeninterner Austausch mit Kolleg*innen auf Englisch Qualifikationen und Anforderungen: [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10190","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}