{"id":10179,"date":"2026-05-20T07:34:34","date_gmt":"2026-05-20T05:34:34","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/karosseriebautechniker-m-w-d-19446\/"},"modified":"2026-07-15T11:55:25","modified_gmt":"2026-07-15T09:55:25","slug":"karosseriebautechniker-m-w-d-19446","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/karosseriebautechniker-m-w-d-19446\/","title":{"rendered":"Karosseriebautechniker  (m\/w\/d)"},"excerpt":{"rendered":"<p>Wir suchen f\u00fcr unseren Kunden in 1190 Wien Karosseriebautechniker (m\/w\/d) zum ehestm\u00f6glichen Eintritt. Aufgabenbereiche: &#8211; Selbstst\u00e4ndige und fachgerechte Arbeitsweise &#8211; Vorbereiten und Lackieren von Fahrzeugteilen &#8211; Instandhaltung und -setzung von Karosserien &#8211; Montieren und Demontieren von Fahrzeugteilen Qualifikationen und Anforderungen: &#8211; Abgeschlossene technische Ausbildung im Bereich KFZ-Karosseriebautechnik und KFZ-Lackierer &#8211; Fundierte Berufserfahrung in diesem Bereich [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10179","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}