{"id":10173,"date":"2026-05-19T10:34:34","date_gmt":"2026-05-19T08:34:34","guid":{"rendered":"https:\/\/transfer-personal.com\/jobs\/zfp-pruefer-iso9712-m-w-d-19439\/"},"modified":"2026-07-15T10:35:24","modified_gmt":"2026-07-15T08:35:24","slug":"zfp-pruefer-iso9712-m-w-d-19439","status":"publish","type":"jobs","link":"https:\/\/transfer-personal.com\/en\/jobs\/zfp-pruefer-iso9712-m-w-d-19439\/","title":{"rendered":"ZfP-Pr\u00fcfer ISO9712 (m\/w\/d)"},"excerpt":{"rendered":"<p>Wir suchen f\u00fcr unseren Kunden in Weiz ZfP-Pr\u00fcfer ISO9712 (m\/w\/d) zum ehestm\u00f6glichen Eintritt. Aufgabenbereiche: &#8211; Durchf\u00fchrung von zerst\u00f6rungsfreien Pr\u00fcfungen &#8211; Durchf\u00fchrung von Kundenabnahmen und Pr\u00fcft\u00e4tigkeiten im Werk Weiz &#8211; Erstellung von Pr\u00fcfberichten Qualifikationen und Anforderungen: &#8211; Abgeschlossene technische Ausbildung (Lehre, HTL \/Werkmeister, FH) im Metallbereich &#8211; Vertiefende Kenntnisse in den Pr\u00fcfverfahren VT, MT, PT, UT [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"template":"","class_list":["post-10173","jobs","type-jobs","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs\/10173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/jobs"}],"about":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/types\/jobs"}],"wp:attachment":[{"href":"https:\/\/transfer-personal.com\/en\/wp-json\/wp\/v2\/media?parent=10173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}